{"id":2457,"date":"2025-10-12T12:18:39","date_gmt":"2025-10-12T06:48:39","guid":{"rendered":"https:\/\/assamtalks.com\/en\/?p=2457"},"modified":"2025-10-12T12:18:39","modified_gmt":"2025-10-12T06:48:39","slug":"caste-certificates-distributed-to-moran-community-along-assam-arunachal-border","status":"publish","type":"post","link":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/","title":{"rendered":"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border"},"content":{"rendered":"<p>TINSUKIA: In a significant development for the Moran community residing along the Assam\u2013Arunachal Pradesh border, caste certificates were distributed to eligible members, recognizing them as permanent residents of Assam or descendants with ancestral roots in the state.<\/p>\n<p>The initiative, which addresses a long-standing demand of the community, was facilitated through the dedicated efforts of Chief Minister Dr. Himanta Biswa Sarma, as highlighted by Pijush Hazarika. Speaking on the occasion, Hazarika expressed satisfaction at fulfilling the long-pending requirement of the Moran community, who had faced numerous challenges over the years.<\/p>\n<p>The distribution ceremony was organised by the Tinsukia District Administration in collaboration with the All Moran Students\u2019 Union, Assam Moran Sabha, and other organisations. The event took place at Balijan Public Auditorium in Philobari, marking a milestone in the community\u2019s recognition and empowerment.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TINSUKIA: In a significant development for the Moran community residing along the Assam\u2013Arunachal Pradesh border, caste certificates were distributed to eligible members, recognizing them as permanent residents of Assam or&hellip;<\/p>\n","protected":false},"author":2,"featured_media":2458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[18],"tags":[],"class_list":["post-2457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border - Assam Talks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border - Assam Talks\" \/>\n<meta property=\"og:description\" content=\"TINSUKIA: In a significant development for the Moran community residing along the Assam\u2013Arunachal Pradesh border, caste certificates were distributed to eligible members, recognizing them as permanent residents of Assam or&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/\" \/>\n<meta property=\"og:site_name\" content=\"Assam Talks\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/assamtalksdigital\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/assamtalksdigital\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-12T06:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/10\/Moran-Community.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Assam Talks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/AssamTalks\" \/>\n<meta name=\"twitter:site\" content=\"@AssamTalks\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Assam Talks\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/\"},\"author\":{\"name\":\"Assam Talks\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#\\\/schema\\\/person\\\/ee76d88c2782346a429d16279b229718\"},\"headline\":\"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border\",\"datePublished\":\"2025-10-12T06:48:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Moran-Community.jpg\",\"articleSection\":[\"Assam\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/\",\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/\",\"name\":\"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border - Assam Talks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Moran-Community.jpg\",\"datePublished\":\"2025-10-12T06:48:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#primaryimage\",\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Moran-Community.jpg\",\"contentUrl\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Moran-Community.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/\",\"name\":\"Assam Talks\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#organization\",\"name\":\"Assam Talks\",\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/AssamTalks_logo.png\",\"contentUrl\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/AssamTalks_logo.png\",\"width\":242,\"height\":88,\"caption\":\"Assam Talks\"},\"image\":{\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/assamtalksdigital\\\/\",\"https:\\\/\\\/x.com\\\/AssamTalks\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/#\\\/schema\\\/person\\\/ee76d88c2782346a429d16279b229718\",\"name\":\"Assam Talks\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/assam-talks-apps-icon-96x96.png\",\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/assam-talks-apps-icon-96x96.png\",\"contentUrl\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/assam-talks-apps-icon-96x96.png\",\"caption\":\"Assam Talks\"},\"description\":\"Assam Talks is an Indian news channel based in Guwahati.\",\"sameAs\":[\"https:\\\/\\\/assamtalks.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/assamtalksdigital\\\/\",\"https:\\\/\\\/x.com\\\/AssamTalks\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/AssamTalks\",\"https:\\\/\\\/www.youtube.com\\\/@assamtalkslive\"],\"url\":\"https:\\\/\\\/assamtalks.com\\\/en\\\/author\\\/assamtalks\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border - Assam Talks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/","og_locale":"en_US","og_type":"article","og_title":"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border - Assam Talks","og_description":"TINSUKIA: In a significant development for the Moran community residing along the Assam\u2013Arunachal Pradesh border, caste certificates were distributed to eligible members, recognizing them as permanent residents of Assam or&hellip;","og_url":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/","og_site_name":"Assam Talks","article_publisher":"https:\/\/www.facebook.com\/assamtalksdigital\/","article_author":"https:\/\/www.facebook.com\/assamtalksdigital\/","article_published_time":"2025-10-12T06:48:39+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/10\/Moran-Community.jpg","type":"image\/jpeg"}],"author":"Assam Talks","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/x.com\/AssamTalks","twitter_site":"@AssamTalks","twitter_misc":{"Written by":"Assam Talks","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#article","isPartOf":{"@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/"},"author":{"name":"Assam Talks","@id":"https:\/\/assamtalks.com\/en\/#\/schema\/person\/ee76d88c2782346a429d16279b229718"},"headline":"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border","datePublished":"2025-10-12T06:48:39+00:00","mainEntityOfPage":{"@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/assamtalks.com\/en\/#organization"},"image":{"@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#primaryimage"},"thumbnailUrl":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/10\/Moran-Community.jpg","articleSection":["Assam"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/","url":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/","name":"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border - Assam Talks","isPartOf":{"@id":"https:\/\/assamtalks.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#primaryimage"},"image":{"@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#primaryimage"},"thumbnailUrl":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/10\/Moran-Community.jpg","datePublished":"2025-10-12T06:48:39+00:00","breadcrumb":{"@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#primaryimage","url":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/10\/Moran-Community.jpg","contentUrl":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/10\/Moran-Community.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/assamtalks.com\/en\/caste-certificates-distributed-to-moran-community-along-assam-arunachal-border\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/assamtalks.com\/en\/"},{"@type":"ListItem","position":2,"name":"Caste Certificates Distributed to Moran Community Along Assam\u2013Arunachal Border"}]},{"@type":"WebSite","@id":"https:\/\/assamtalks.com\/en\/#website","url":"https:\/\/assamtalks.com\/en\/","name":"Assam Talks","description":"","publisher":{"@id":"https:\/\/assamtalks.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/assamtalks.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/assamtalks.com\/en\/#organization","name":"Assam Talks","url":"https:\/\/assamtalks.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/assamtalks.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/06\/AssamTalks_logo.png","contentUrl":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/06\/AssamTalks_logo.png","width":242,"height":88,"caption":"Assam Talks"},"image":{"@id":"https:\/\/assamtalks.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/assamtalksdigital\/","https:\/\/x.com\/AssamTalks"]},{"@type":"Person","@id":"https:\/\/assamtalks.com\/en\/#\/schema\/person\/ee76d88c2782346a429d16279b229718","name":"Assam Talks","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/06\/assam-talks-apps-icon-96x96.png","url":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/06\/assam-talks-apps-icon-96x96.png","contentUrl":"https:\/\/assamtalks.com\/en\/wp-content\/uploads\/2025\/06\/assam-talks-apps-icon-96x96.png","caption":"Assam Talks"},"description":"Assam Talks is an Indian news channel based in Guwahati.","sameAs":["https:\/\/assamtalks.com\/","https:\/\/www.facebook.com\/assamtalksdigital\/","https:\/\/x.com\/AssamTalks","https:\/\/x.com\/https:\/\/x.com\/AssamTalks","https:\/\/www.youtube.com\/@assamtalkslive"],"url":"https:\/\/assamtalks.com\/en\/author\/assamtalks\/"}]}},"_links":{"self":[{"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/posts\/2457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/comments?post=2457"}],"version-history":[{"count":1,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/posts\/2457\/revisions"}],"predecessor-version":[{"id":2459,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/posts\/2457\/revisions\/2459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/media\/2458"}],"wp:attachment":[{"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/media?parent=2457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/categories?post=2457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/assamtalks.com\/en\/wp-json\/wp\/v2\/tags?post=2457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}